{"id":208953,"date":"2019-05-30T00:05:08","date_gmt":"2019-05-30T03:05:08","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=208953"},"modified":"2019-05-30T16:11:36","modified_gmt":"2019-05-30T19:11:36","slug":"mp-do-pente-fino-passa-na-camara-em-cima-da-hora","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/mp-do-pente-fino-passa-na-camara-em-cima-da-hora\/","title":{"rendered":"MP do &#8216;Pente Fino&#8217; passa na C\u00e2mara na hora H"},"content":{"rendered":"<p>Os deputados aprovaram na noite desta quarta, 29, a Medida Provis\u00f3ria 871, conhecida como MP do Pente Fino. A medida provis\u00f3ria cria um programa de revis\u00e3o de benef\u00edcios do Instituto Nacional do Seguro Social.<\/p>\n<p>Tamb\u00e9m imp\u00f5e a necessidade de cadastro do trabalhador rural e restringe o pagamento de aux\u00edlio-reclus\u00e3o apenas aos casos de pena em regime fechado.<\/p>\n<p>Mas, apesar dos esfor\u00e7os da C\u00e2mara, a MP ainda corre o risco de perder o efeito. \u00c9 que o texto caduca na pr\u00f3xima segunda-feira, 3, e precisa ainda ser votada no Senado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os deputados aprovaram na noite desta quarta, 29, a Medida Provis\u00f3ria 871, conhecida como MP do Pente Fino. A medida provis\u00f3ria cria um programa de revis\u00e3o de benef\u00edcios do Instituto Nacional do Seguro Social. Tamb\u00e9m imp\u00f5e a necessidade de cadastro do trabalhador rural e restringe o pagamento de aux\u00edlio-reclus\u00e3o apenas aos casos de pena em [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":208205,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[],"class_list":["post-208953","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/208953","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=208953"}],"version-history":[{"count":2,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/208953\/revisions"}],"predecessor-version":[{"id":209009,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/208953\/revisions\/209009"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/208205"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=208953"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=208953"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=208953"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}