{"id":209233,"date":"2019-06-04T08:32:03","date_gmt":"2019-06-04T11:32:03","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=209233"},"modified":"2019-06-04T08:32:03","modified_gmt":"2019-06-04T11:32:03","slug":"vai-aos-eua-se-postou-bobagem-ta-no-sal","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/vai-aos-eua-se-postou-bobagem-ta-no-sal\/","title":{"rendered":"Vai aos EUA? Se postou bobagem t\u00e1 no sal"},"content":{"rendered":"<p>O Departamento de Estado americano passou a requerer de quase todos os solicitantes de visto que prestem informa\u00e7\u00f5es sobre suas contas em redes sociais e outros detalhes pessoais.<\/p>\n<p>As autoridades explicam que a nova exig\u00eancia \u00e9 uma medida antiterrorista, mas cr\u00edticos manifestam s\u00e9rias preocupa\u00e7\u00f5es com a liberdade de express\u00e3o.<\/p>\n<p>Solicitantes de visto para os Estados Unidos (EUA) precisam agora comunicar o nome das contas que tenham mantido em redes sociais, como Twitter e Facebook, nos \u00faltimos cinco anos.<\/p>\n<p>O Departamento de Estado tamb\u00e9m pede o n\u00famero de telefone e os endere\u00e7os de e-mail do solicitante correspondentes ao mesmo per\u00edodo.<\/p>\n<p>Cidad\u00e3os de 38 pa\u00edses e territ\u00f3rios s\u00e3o autorizados a viajar sem visto para os Estados Unidos a passeio ou neg\u00f3cios por at\u00e9 90 dias.<\/p>\n<p>No entanto, necessitam de visto solicitantes que planejem estadias mais longas, cidad\u00e3os de outros pa\u00edses e territ\u00f3rios e quem pretenda imigrar para os Estados Unidos.<\/p>\n<p>Segundo \u00f3rg\u00e3os de m\u00eddia americanos, estima-se que a cada ano 15 milh\u00f5es de pessoas ser\u00e3o afetadas pela mudan\u00e7a \u2014 proposta no ano passado pelo governo Trump.<\/p>\n<p>A Uni\u00e3o Americana de Liberdades Civis criticou a medida, com o argumento de que ela ter\u00e1 efeito desencorajador sobre a liberdade de express\u00e3o. Para a entidade, \u00e9 muito prov\u00e1vel que, cientes de serem observadas pelo governo, as pessoas passem a se autocensurar online.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Departamento de Estado americano passou a requerer de quase todos os solicitantes de visto que prestem informa\u00e7\u00f5es sobre suas contas em redes sociais e outros detalhes pessoais. As autoridades explicam que a nova exig\u00eancia \u00e9 uma medida antiterrorista, mas cr\u00edticos manifestam s\u00e9rias preocupa\u00e7\u00f5es com a liberdade de express\u00e3o. Solicitantes de visto para os Estados [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":129079,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-209233","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasilia"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/209233","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=209233"}],"version-history":[{"count":1,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/209233\/revisions"}],"predecessor-version":[{"id":209234,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/209233\/revisions\/209234"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/129079"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=209233"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=209233"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=209233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}