{"id":209407,"date":"2019-06-07T13:50:56","date_gmt":"2019-06-07T16:50:56","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=209407"},"modified":"2019-06-07T13:50:56","modified_gmt":"2019-06-07T16:50:56","slug":"socorro-detran-ligue-para-197-e-chame-a-policia","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/socorro-detran-ligue-para-197-e-chame-a-policia\/","title":{"rendered":"Socorro, Detran! Ligue para 197 e chame a pol\u00edcia"},"content":{"rendered":"<p>\u00c1guas Claras, pouco depois do meio-dia e meia desta sexta-feira, 6. No estacionamento de um dos shoppings da cidade que \u00e9 considerada o para\u00edso da classe m\u00e9dia de Bras\u00edlia, o inacredit\u00e1vel acontece.<\/p>\n<p>Flagrante desrespeito \u00e0s leis. E ningu\u00e9m pior do que a pol\u00edcia &#8211; guardi\u00e3, junto com o Judici\u00e1rio, dos direitos do cidad\u00e3o -, para burlar a sociedade que paga os altos impostos transformados nos sal\u00e1rios dessa categoria &#8211; a mais bem paga o Pa\u00eds.<\/p>\n<p>O gesto insano do motorista do ve\u00edculo oficial de placas DVT 0358-DF, causou revolta. E congestionamento no estacionamento p\u00fablico. pois os verdadeiros motoristas com direito de uso de vagas especiais, se negavam a recuar ou seguir adiante com seus carros.<\/p>\n<p>O ve\u00edculo policial, C 1316, est\u00e1 destinado ao uso de policiais da 13\u00aa Delegacia Policial. Essa DP est\u00e1 localizada em Sobradinho, cidade-sat\u00e9lite de Bras\u00edlia no outro extremo de \u00c1guas Claras.<\/p>\n<p>Dentro do shopping, a fila da lot\u00e9rica dava voltas (s\u00e1bado \u00e9 dia de Mega acumulada), a Pra\u00e7a de Alimenta\u00e7\u00e3o estava lotada e os bancos, para variar, com filas imensas. Procurada para explica\u00e7\u00f5es,\u00a0 ningu\u00e9m na 13\u00aa DP atendeu ao telefonema.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c1guas Claras, pouco depois do meio-dia e meia desta sexta-feira, 6. No estacionamento de um dos shoppings da cidade que \u00e9 considerada o para\u00edso da classe m\u00e9dia de Bras\u00edlia, o inacredit\u00e1vel acontece. Flagrante desrespeito \u00e0s leis. E ningu\u00e9m pior do que a pol\u00edcia &#8211; guardi\u00e3, junto com o Judici\u00e1rio, dos direitos do cidad\u00e3o -, para [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":209408,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[95],"class_list":["post-209407","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasilia","tag-capa"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/209407","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=209407"}],"version-history":[{"count":1,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/209407\/revisions"}],"predecessor-version":[{"id":209409,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/209407\/revisions\/209409"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/209408"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=209407"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=209407"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=209407"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}