{"id":209446,"date":"2019-06-08T16:24:38","date_gmt":"2019-06-08T19:24:38","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=209446"},"modified":"2019-06-09T13:25:57","modified_gmt":"2019-06-09T16:25:57","slug":"estudante-deixa-problemas-la-fora-e-alivia-mente","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/estudante-deixa-problemas-la-fora-e-alivia-mente\/","title":{"rendered":"Estudante esquece problemas e alivia mente"},"content":{"rendered":"<p>Duas sess\u00f5es di\u00e1rias de cerca de 15 minutos de olhos fechados prestando aten\u00e7\u00e3o no que acontece na mente e no corpo, deixando de lado o restante do mundo, s\u00e3o suficientes para melhorar a concentra\u00e7\u00e3o, a criatividade e a capacidade de tomar decis\u00f5es, de acordo com o diretor da Sociedade Internacional de Medita\u00e7\u00e3o do Rio de Janeiro, Kleb\u00e9r Tani.<\/p>\n<p>Em busca desses benef\u00edcios para estudantes e professores, institui\u00e7\u00f5es de ensino superior recorrem a cursos de medita\u00e7\u00e3o e incentivam a pr\u00e1tica no ambiente acad\u00eamico.<\/p>\n<p>Tani aplica no Brasil as t\u00e9cnicas da medita\u00e7\u00e3o transcendental, como associado da Funda\u00e7\u00e3o David Lynch, organiza\u00e7\u00e3o internacional fundada pelo diretor cinematogr\u00e1fico que carrega no curr\u00edculo produ\u00e7\u00f5es como O Homem-Elefante e Veludo Azul. H\u00e1 42 anos ele trabalha levando a t\u00e9cnica a atletas, a pres\u00eddios e a pessoas em situa\u00e7\u00e3o de vulnerabilidade social. Recentemente, h\u00e1 15 anos, a \u00e1rea educacional ganhou espa\u00e7o e, com ela, o ensino superior.<\/p>\n<p>Institui\u00e7\u00f5es como o Centro Federal de Educa\u00e7\u00e3o Tecnol\u00f3gica Celso Suckow da Fonseca (Cefet\/RJ) e a UniCarioca s\u00e3o clientes de Tani. \u201cEssas pequenas aptid\u00f5es, nas universidades, est\u00e3o sendo muito enfatizadas. N\u00e3o adianta formar um engenheiro ou um economista se a pessoa \u00e9 um ser humano ca\u00eddo, que trata mal a fam\u00edlia, \u00e9 uma pessoa n\u00e3o \u00e9tica\u201d, explica.<\/p>\n<p>As aulas s\u00e3o ofertadas de forma optativa para professores e estudantes. Eles t\u00eam cinco dias de forma\u00e7\u00e3o e depois \u00e9 feito um acompanhamento. Cabe a eles colocar em pr\u00e1tica a medita\u00e7\u00e3o por cerca de 15 minutos duas vezes por dia. O objetivo \u00e9 que a pessoa consiga olhar para si, identificar os pr\u00f3prios pensamentos e conseguir perceber aqueles que s\u00e3o \u201c\u00fateis\u201d e os que apenas geram ansiedade.<\/p>\n<p>\u201cOs programas da educa\u00e7\u00e3o s\u00e3o muito voltados para fora. A ideia \u00e9 continuar com isso, mas trabalhar tamb\u00e9m o desenvolvimento do conhecedor, que \u00e9 o estudante\u201d, diz Tani.<\/p>\n<p>\u201cQuanto mais sil\u00eancio se experimenta na mente, mais capacidade de filtrar os pensamentos. Pensamentos \u00fateis ser\u00e3o reconhecidos mais facilmente e pensamentos in\u00fateis ser\u00e3o eliminados mais facilmente. O custo operacional melhora muito, desenvolve-se uma vis\u00e3o de pensamento com mais objetividade, mais sentido. E com isso, perde-se menos dinheiro, menos tempo e menos energia porque n\u00e3o se sai atirando para todos os lados\u201d, ensina.<\/p>\n<p>Segundo o professor, as pessoas est\u00e3o cada vez mais cansadas. \u201cParece que ficar quieto \u00e9 perda de tempo. Para ser um indiv\u00edduo mais efetivo no que eu fa\u00e7o, tenho que ser uma pessoa sempre tensa\u201d, diz. Nos estudos, a medita\u00e7\u00e3o, segundo Tani, aumenta a capacidade de aprendizagem e melhora o desempenho acad\u00eamico.<\/p>\n<p>A t\u00e9cnica serve tamb\u00e9m para que o indiv\u00edduo desenvolva uma vis\u00e3o mais ampla de mundo e consiga se colocar no lugar das pessoas que est\u00e3o ao seu redor, de acordo com o professor.<\/p>\n<p>A quest\u00e3o foi um dos temas centrais no XII Congresso Brasileiro da Educa\u00e7\u00e3o Superior Particular, em Belo Horizonte, onde Tani foi um dos palestrantes.<\/p>\n<p>Neste ano, o congresso teve como tema Educa\u00e7\u00e3o Superior: Inova\u00e7\u00e3o e Diversidade na Constru\u00e7\u00e3o de um Brasil Plural. Ao longo do encontro houve espa\u00e7o para o debate sobre pluralidade \u00e9tnica, cultural e de g\u00eanero, tanto com rela\u00e7\u00e3o aos estudantes quanto aos professores e t\u00e9cnicos administrativos.<\/p>\n<p>\u201cO congresso partiu da premissa de que a inova\u00e7\u00e3o e o desenvolvimento institucional dependem de um corpo diverso de docentes, discentes e t\u00e9cnicos administrativos\u201d, diz carta divulgada ao fim do evento pelo setor privado de educa\u00e7\u00e3o, representado pelo F\u00f3rum das Entidades Representativas do Ensino Superior Particular.<\/p>\n<p>Segundo o f\u00f3rum, vivemos em um pa\u00eds diverso. \u201cAqui, nativos e imigrantes, homens e mulheres, brancos e negros convivem em harmonia nos mais diversos espa\u00e7os sociais, inclusive nas universidades. Na esfera econ\u00f4mica, a diversidade j\u00e1 se mostrou fundamental para a produtividade e o progresso. N\u00e3o faltam exemplos de pa\u00edses que t\u00eam na diversidade da popula\u00e7\u00e3o sua fonte de riqueza e de impulsionamento do crescimento\u201d, afirma.<\/p>\n<p>A medita\u00e7\u00e3o ajuda no desenvolvimento das chamadas habilidades s\u00f3cio-emocionais, como empatia, a capacidade de di\u00e1logo de resolver conflitos, entre outros pontos. Voltar o ensino para essas compet\u00eancias \u00e9 algo que tem sido feito em v\u00e1rias partes do mundo.<\/p>\n<p>A Base Nacional Comum Curricular (BNCC), aprovada pelo Brasil em 2017 para o ensino infantil e fundamental e, em 2018, para o ensino m\u00e9dio, prev\u00ea que em todo o per\u00edodo escolar sejam desenvolvidas, al\u00e9m de capacidades acad\u00eamicas, tamb\u00e9m habilidades s\u00f3cio-emocionais.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Duas sess\u00f5es di\u00e1rias de cerca de 15 minutos de olhos fechados prestando aten\u00e7\u00e3o no que acontece na mente e no corpo, deixando de lado o restante do mundo, s\u00e3o suficientes para melhorar a concentra\u00e7\u00e3o, a criatividade e a capacidade de tomar decis\u00f5es, de acordo com o diretor da Sociedade Internacional de Medita\u00e7\u00e3o do Rio de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":209447,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[],"class_list":["post-209446","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/209446","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=209446"}],"version-history":[{"count":2,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/209446\/revisions"}],"predecessor-version":[{"id":209506,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/209446\/revisions\/209506"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/209447"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=209446"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=209446"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=209446"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}