{"id":209568,"date":"2019-06-10T19:04:53","date_gmt":"2019-06-10T22:04:53","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=209568"},"modified":"2019-06-10T19:46:57","modified_gmt":"2019-06-10T22:46:57","slug":"oposicao-decide-obstruir-votacoes-na-camara","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/oposicao-decide-obstruir-votacoes-na-camara\/","title":{"rendered":"Oposi\u00e7\u00e3o decide obstruir vota\u00e7\u00f5es na C\u00e2mara"},"content":{"rendered":"<p>L\u00edderes de partidos de oposi\u00e7\u00e3o (PT, Psol e PCdoB) anunciaram nesta segunda-feira (10) obstru\u00e7\u00e3o total nas vota\u00e7\u00f5es da C\u00e2mara dos Deputados, ap\u00f3s a divulga\u00e7\u00e3o de mensagens atribu\u00eddas ao atual ministro da Justi\u00e7a e Seguran\u00e7a P\u00fablica, Sergio Moro, e a membros da for\u00e7a-tarefa da Lava Jato pelo site de not\u00edcias The Intercept.<\/p>\n<p>Em texto que acompanha a publica\u00e7\u00e3o das tr\u00eas reportagens divulgadas ontem, o Intercept Brasil sustenta que o teor das mensagens indica \u201ccomportamentos anti\u00e9ticos e transgress\u00f5es que o Brasil e o mundo t\u00eam o direito de conhecer\u201d. Segundo o site, s\u00e3o \u201cdiscuss\u00f5es internas e atitudes altamente controversas, politizadas e legalmente duvidosas da for\u00e7a-tarefa da Lava Jato.\u201d<\/p>\n<p>Segundo a l\u00edder da minoria, deputada Jandira Feghali (PCdoB-RJ), partidos da oposi\u00e7\u00e3o se unir\u00e3o para inviabilizar todas as atividades na C\u00e2mara como forma de pressionar a ado\u00e7\u00e3o de medidas. Os parlamentares pedem a ren\u00fancia de Sergio Moro do cargo de ministro, o afastamento de procuradores da Lava Jato Deltan Dallagnol e Laura Tessler, al\u00e9m da per\u00edcia de telefones funcionais desses procuradores. \u201cIremos obstruir todas as pautas enquanto n\u00e3o forem tomadas provid\u00eancias. N\u00e3o vamos votar nada at\u00e9 que medidas sejam tomadas\u201d.<\/p>\n<p>Uma nova reuni\u00e3o com l\u00edderes de partidos da oposi\u00e7\u00e3o est\u00e1 marcada para esta ter\u00e7a-feira (11), na sede do PSB, em Bras\u00edlia, \u00e0s 10h30. Segundo Feghali, o grupo de parlamentares est\u00e1 procurando di\u00e1logo com deputados dos partidos de Centro e o presidente da C\u00e2mara, deputado Rodrigo Maia (DEM-RJ).<\/p>\n<p><strong>Base aliada<\/strong><br \/>\nA Frente Parlamentar da Seguran\u00e7a P\u00fablica divulgou um manifesto em apoio aos procuradores da opera\u00e7\u00e3o Lava Jato e ao ministro Sergio Moro. Assinado pelo coordenador da Frente Parlamentar, deputado Capit\u00e3o Augusto (PL-SP), o documento afirma que n\u00e3o se pode deixar que a \u201copera\u00e7\u00e3o, as institui\u00e7\u00f5es e seus membros, sejam enfraquecidos ou desmoralizados\u201d.<\/p>\n<p>\u201cA divulga\u00e7\u00e3o de trechos atribu\u00eddos \u00e0s autoridades p\u00fablicas em vez de causar esp\u00e9cie diante da utiliza\u00e7\u00e3o de meios escusos, criminosos e violentamente contra a nossa Constitui\u00e7\u00e3o para a sua obten\u00e7\u00e3o, pasmem, ganhou destaque na m\u00eddia sob a insinua\u00e7\u00e3o de que os trechos livremente manipulados pelo duvidoso site dariam conta de p\u00f4r em cheque a credibilidade da opera\u00e7\u00e3o e dos agentes p\u00fablicos envolvidos\u201d, diz o manifesto.<\/p>\n<p>O documento ressalta ainda que a opera\u00e7\u00e3o Lava Jato \u201c\u00e9 a maior investiga\u00e7\u00e3o de corrup\u00e7\u00e3o e lavagem de dinheiro que o mundo j\u00e1 teve\u201d. \u201cO volume de recursos desviados, conforme apurado, est\u00e1 na casa de bilh\u00f5es de reais. Soma-se a isso a express\u00e3o econ\u00f4mica e pol\u00edtica dos suspeitos de participar do esquema de corrup\u00e7\u00e3o\u201d, completa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u00edderes de partidos de oposi\u00e7\u00e3o (PT, Psol e PCdoB) anunciaram nesta segunda-feira (10) obstru\u00e7\u00e3o total nas vota\u00e7\u00f5es da C\u00e2mara dos Deputados, ap\u00f3s a divulga\u00e7\u00e3o de mensagens atribu\u00eddas ao atual ministro da Justi\u00e7a e Seguran\u00e7a P\u00fablica, Sergio Moro, e a membros da for\u00e7a-tarefa da Lava Jato pelo site de not\u00edcias The Intercept. Em texto que acompanha [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":209569,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[],"class_list":["post-209568","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/209568","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=209568"}],"version-history":[{"count":1,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/209568\/revisions"}],"predecessor-version":[{"id":209570,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/209568\/revisions\/209570"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/209569"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=209568"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=209568"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=209568"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}