{"id":325,"date":"2014-02-04T17:36:02","date_gmt":"2014-02-04T20:36:02","guid":{"rendered":"http:\/\/www.notibras.com\/site\/?p=325"},"modified":"2014-02-04T17:58:55","modified_gmt":"2014-02-04T20:58:55","slug":"saco-de-bondades-para-as-empresas-de-energia-eletrica","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/saco-de-bondades-para-as-empresas-de-energia-eletrica\/","title":{"rendered":"Pronto. Um saco de bondades para as empresas de energia el\u00e9trica"},"content":{"rendered":"<p>O que o cidad\u00e3o brasileiro n\u00e3o aceita mais \u00e9 a benevol\u00eancia, para se dizer o m\u00ednimo, com que as empresas el\u00e9tricas s\u00e3o tratadas pelo Governo Federal.<\/p>\n<p>Dois pesos e duas medidas. Enquanto a popula\u00e7\u00e3o brasileira, e ai n\u00e3o somente o consumidor, sofre e \u00e9 prejudicado com a queda vertiginosa da qualidade do servi\u00e7o el\u00e9trico oferecido e com as altas tarifas, muito pouco \u00e9 feito para reverter essa situa\u00e7\u00e3o; j\u00e1 que sistematicamente as empresas el\u00e9tricas de gera\u00e7\u00e3o, transmiss\u00e3o e distribui\u00e7\u00e3o s\u00e3o \u201caliviadas\u201d dos compromissos, inclusive contratuais, por quem devia regul\u00e1-las fiscalizar.<\/p>\n<p>Os \u201capag\u00f5es\u201d e \u201capaguinhos\u201d j\u00e1 s\u00e3o constantes na vida das pessoas, que sofrem as consequ\u00eancias de um p\u00e9ssimo servi\u00e7o prestado. Carente de manuten\u00e7\u00e3o, de investimentos de moderniza\u00e7\u00e3o, de qualifica\u00e7\u00e3o da m\u00e3o de obra, de incompet\u00eancia gerencial e com lucros cada vez maiores (basta acompanhar a evolu\u00e7\u00e3o dos balan\u00e7os cont\u00e1beis anuais), essas empresas ainda pressionam, e conseguem com os gestores de plant\u00e3o, mais e mais benef\u00edcios. O que se resume a um \u201ccapitalismo sem risco\u201d para quem est\u00e1, ou aventurou-se, nesse negocio. E n\u00e3o s\u00e3o poucos os aventureiros de primeira viagem.<\/p>\n<p>A popula\u00e7\u00e3o sofre as mazelas de ter as frequentes interrup\u00e7\u00f5es de energia j\u00e1 incorporadas a seu cotidiano e tudo o que isso acarreta; e mesmo assim ter que pagar tarifas caras (ai de quem n\u00e3o pagar ou atrasar o pagamento).<\/p>\n<p>Vejamos ent\u00e3o mais recentemente algumas medidas que constituem verdadeiro \u201csaco de bondades\u201d oferecidas \u00e0quelas empresas.<\/p>\n<p>No setor de gera\u00e7\u00e3o, a resolu\u00e7\u00e3o da Agencia Nacional de Energia El\u00e9trica (Aneel) n\u00ba 595\/2013, de dezembro passado, prev\u00ea algumas \u201cbondades\u201d. Por exemplo, a toler\u00e2ncia de tr\u00eas meses de atraso para a aplica\u00e7\u00e3o de san\u00e7\u00f5es e a exclus\u00e3o de responsabilidades ao gerador nas situa\u00e7\u00f5es em que o atraso na opera\u00e7\u00e3o ocorrer por caso \u201cfortuito\u201d ou \u201cfor\u00e7a maior\u201d (?). Tamb\u00e9m poder\u00e1 repassar ao consumidor o valor integral da energia comprada no mercado para atender a seus compromissos. O que significa que o consumidor vai pagar, pela inefici\u00eancia das empresas, que deixaram de produzir a quantidade de energia contratada no tempo determinado. Complementando sua quota de gera\u00e7\u00e3o com a compra de energia \u00e0s termel\u00e9tricas (energia mais cara), repassando o aumento do pre\u00e7o da energia da\u00ed resultante ao Governo Federal, e assim aos contribuintes (n\u00f3s). Na resolu\u00e7\u00e3o anterior de 2005, a de no 165, as regras eram mais severas, pois as geradoras, quando atrasassem seus compromissos, n\u00e3o podiam repassar aos consumidores os gastos extras.<\/p>\n<p>Na transmiss\u00e3o, segundo relat\u00f3rio da Aneel, os atrasos chegam a 4 (quatro) anos. Na m\u00e9dia, o descumprimento do cronograma supera em 13 meses o prazo original previsto no contrato de concess\u00e3o. 71% de todas as obras de transmiss\u00e3o est\u00e3o com o cronograma atrasado. Ou, das 129 companhias do setor de transmiss\u00e3o, 57 apresentaram atrasos no cronograma de obras. O documento avaliou as obras conclu\u00eddas ap\u00f3s dezembro de 2010 e as que estavam em andamento at\u00e9 dezembro do ano passado. O resultado mostrou uma piora gradual no setor nos \u00faltimos anos. De acordo com a legisla\u00e7\u00e3o, a empresa que tiver mais de tr\u00eas autos de infra\u00e7\u00e3o e atraso acima de 180 dias n\u00e3o pode participar, sozinha, de novos leil\u00f5es de energia. A campe\u00e3 nesse quesito \u00e9 a estatal Chesf, com 17 autos de infra\u00e7\u00e3o. E nada \u00e9 feito para modificar tamanha incompet\u00eancia e falta de planejamento.<\/p>\n<p>Na distribui\u00e7\u00e3o, o \u201clobby\u201d \u00e9 estruturado e organizado. Capitaneados pela Associa\u00e7\u00e3o Brasileira de Distribuidores de Energia El\u00e9trica (Abradee), constantes benesses t\u00eam sido \u201cconquistadas\u201d. A mais recente \u00e9 a proposta de firmar Termo de Compromisso de Ajuste de Conduta (TAC) entre a Aneel e as concession\u00e1rias, permission\u00e1rias e autorizadas de servi\u00e7os e instala\u00e7\u00f5es de energia. O TAC poder\u00e1 ser firmado quando forem encontrados descumprimentos quanto \u00e0 qualidade dos servi\u00e7os de energia el\u00e9trica, a seguran\u00e7a das pessoas e das instala\u00e7\u00f5es de energia, a expans\u00e3o, refor\u00e7os e melhorias das redes de energia, assim como dos sistemas de prote\u00e7\u00e3o e controle do sistema el\u00e9trico. Tamb\u00e9m ser\u00e1 poss\u00edvel, em alternativa \u00e0 aplica\u00e7\u00e3o de multas, impor \u00e0s concession\u00e1rias pena substitutiva consistente em Obriga\u00e7\u00e3o de Realiza\u00e7\u00e3o de A\u00e7\u00f5es e Investimentos. O pedido de imposi\u00e7\u00e3o de pena substitutiva ser\u00e1 apreciado pela Diretoria da Aneel e, se aprovado, a concession\u00e1ria ter\u00e1 o prazo de 30 dias para apresentar a descri\u00e7\u00e3o e o cronograma detalhado das a\u00e7\u00f5es e investimentos a serem implementados. Ou seja, ser\u00e1 uma alternativa dada \u00e0s distribuidoras, em lugar da continuidade de processo fiscalizat\u00f3rio ou punitivo.<\/p>\n<p>Enquanto que o cidad\u00e3o convive com a p\u00e9ssima presta\u00e7\u00e3o de servi\u00e7o, as companhias s\u00e3o agraciadas, favorecidas e estimuladas pelo poder publico com \u201cfacilidades\u201d para continuarem a \u201cdesrespeitar\u201d os que necessitam de energia el\u00e9trica (n\u00f3s de novo). \u00c9 hora de dar um basta. A solu\u00e7\u00e3o est\u00e1 com o povo (n\u00f3s finalmente).<\/p>\n<p><strong>* Heitor Scalambrini Costa<\/strong><br \/>\n<strong>Professor da Universidade Federal de Pernambuco<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O que o cidad\u00e3o brasileiro n\u00e3o aceita mais \u00e9 a benevol\u00eancia, para se dizer o m\u00ednimo, com que as empresas el\u00e9tricas s\u00e3o tratadas pelo Governo Federal. Dois pesos e duas medidas. Enquanto a popula\u00e7\u00e3o brasileira, e ai n\u00e3o somente o consumidor, sofre e \u00e9 prejudicado com a queda vertiginosa da qualidade do servi\u00e7o el\u00e9trico oferecido [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":326,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[25],"tags":[],"tmauthors":[],"class_list":["post-325","post","type-post","status-publish","format-standard","has-post-thumbnail","category-opina-ai"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pronto. Um saco de bondades para as empresas de energia el\u00e9trica - Notibras<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.notibras.com\/site\/saco-de-bondades-para-as-empresas-de-energia-eletrica\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pronto. Um saco de bondades para as empresas de energia el\u00e9trica - Notibras\" \/>\n<meta property=\"og:description\" content=\"O que o cidad\u00e3o brasileiro n\u00e3o aceita mais \u00e9 a benevol\u00eancia, para se dizer o m\u00ednimo, com que as empresas el\u00e9tricas s\u00e3o tratadas pelo Governo Federal. Dois pesos e duas medidas. Enquanto a popula\u00e7\u00e3o brasileira, e ai n\u00e3o somente o consumidor, sofre e \u00e9 prejudicado com a queda vertiginosa da qualidade do servi\u00e7o el\u00e9trico oferecido [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.notibras.com\/site\/saco-de-bondades-para-as-empresas-de-energia-eletrica\/\" \/>\n<meta property=\"og:site_name\" content=\"Notibras\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/notibras\/\" \/>\n<meta property=\"article:published_time\" content=\"2014-02-04T20:36:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2014-02-04T20:58:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.notibras.com\/site\/wp-content\/uploads\/2014\/02\/energia-20111129075906.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"680\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Notibras\" \/>\n<meta name=\"twitter:site\" content=\"@Notibras\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/saco-de-bondades-para-as-empresas-de-energia-eletrica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/saco-de-bondades-para-as-empresas-de-energia-eletrica\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#\\\/schema\\\/person\\\/36ab0979449956132d3e5b517ea76ac8\"},\"headline\":\"Pronto. Um saco de bondades para as empresas de energia el\u00e9trica\",\"datePublished\":\"2014-02-04T20:36:02+00:00\",\"dateModified\":\"2014-02-04T20:58:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/saco-de-bondades-para-as-empresas-de-energia-eletrica\\\/\"},\"wordCount\":878,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/saco-de-bondades-para-as-empresas-de-energia-eletrica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/energia-20111129075906.jpg\",\"articleSection\":[\"Opina a\u00ed\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.notibras.com\\\/site\\\/saco-de-bondades-para-as-empresas-de-energia-eletrica\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/saco-de-bondades-para-as-empresas-de-energia-eletrica\\\/\",\"url\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/saco-de-bondades-para-as-empresas-de-energia-eletrica\\\/\",\"name\":\"Pronto. Um saco de bondades para as empresas de energia el\u00e9trica - Notibras\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/saco-de-bondades-para-as-empresas-de-energia-eletrica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/saco-de-bondades-para-as-empresas-de-energia-eletrica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/energia-20111129075906.jpg\",\"datePublished\":\"2014-02-04T20:36:02+00:00\",\"dateModified\":\"2014-02-04T20:58:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/saco-de-bondades-para-as-empresas-de-energia-eletrica\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.notibras.com\\\/site\\\/saco-de-bondades-para-as-empresas-de-energia-eletrica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/saco-de-bondades-para-as-empresas-de-energia-eletrica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/energia-20111129075906.jpg\",\"contentUrl\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/energia-20111129075906.jpg\",\"width\":680,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/saco-de-bondades-para-as-empresas-de-energia-eletrica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pronto. Um saco de bondades para as empresas de energia el\u00e9trica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/\",\"name\":\"Notibras\",\"description\":\"Not\u00edcias de Bras\u00edlia, do Brasil e do Mundo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#organization\",\"name\":\"Grupo Notibras de Comunica\u00e7\u00e3o\",\"url\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/notibras23.png\",\"contentUrl\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/notibras23.png\",\"width\":350,\"height\":87,\"caption\":\"Grupo Notibras de Comunica\u00e7\u00e3o\"},\"image\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/notibras\\\/\",\"https:\\\/\\\/x.com\\\/Notibras\",\"https:\\\/\\\/www.instagram.com\\\/notibras\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#\\\/schema\\\/person\\\/36ab0979449956132d3e5b517ea76ac8\",\"name\":\"Reda\u00e7\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e0a867bdedb85fd243eadf09663511f96fc81e0720a4a42581f334ad4303aa6b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e0a867bdedb85fd243eadf09663511f96fc81e0720a4a42581f334ad4303aa6b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e0a867bdedb85fd243eadf09663511f96fc81e0720a4a42581f334ad4303aa6b?s=96&d=mm&r=g\",\"caption\":\"Reda\u00e7\u00e3o\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pronto. Um saco de bondades para as empresas de energia el\u00e9trica - Notibras","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.notibras.com\/site\/saco-de-bondades-para-as-empresas-de-energia-eletrica\/","og_locale":"pt_BR","og_type":"article","og_title":"Pronto. Um saco de bondades para as empresas de energia el\u00e9trica - Notibras","og_description":"O que o cidad\u00e3o brasileiro n\u00e3o aceita mais \u00e9 a benevol\u00eancia, para se dizer o m\u00ednimo, com que as empresas el\u00e9tricas s\u00e3o tratadas pelo Governo Federal. Dois pesos e duas medidas. Enquanto a popula\u00e7\u00e3o brasileira, e ai n\u00e3o somente o consumidor, sofre e \u00e9 prejudicado com a queda vertiginosa da qualidade do servi\u00e7o el\u00e9trico oferecido [&hellip;]","og_url":"https:\/\/www.notibras.com\/site\/saco-de-bondades-para-as-empresas-de-energia-eletrica\/","og_site_name":"Notibras","article_publisher":"https:\/\/www.facebook.com\/notibras\/","article_published_time":"2014-02-04T20:36:02+00:00","article_modified_time":"2014-02-04T20:58:55+00:00","og_image":[{"width":680,"height":500,"url":"https:\/\/www.notibras.com\/site\/wp-content\/uploads\/2014\/02\/energia-20111129075906.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o","twitter_card":"summary_large_image","twitter_creator":"@Notibras","twitter_site":"@Notibras","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.notibras.com\/site\/saco-de-bondades-para-as-empresas-de-energia-eletrica\/#article","isPartOf":{"@id":"https:\/\/www.notibras.com\/site\/saco-de-bondades-para-as-empresas-de-energia-eletrica\/"},"author":{"name":"Reda\u00e7\u00e3o","@id":"https:\/\/www.notibras.com\/site\/#\/schema\/person\/36ab0979449956132d3e5b517ea76ac8"},"headline":"Pronto. Um saco de bondades para as empresas de energia el\u00e9trica","datePublished":"2014-02-04T20:36:02+00:00","dateModified":"2014-02-04T20:58:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.notibras.com\/site\/saco-de-bondades-para-as-empresas-de-energia-eletrica\/"},"wordCount":878,"commentCount":0,"publisher":{"@id":"https:\/\/www.notibras.com\/site\/#organization"},"image":{"@id":"https:\/\/www.notibras.com\/site\/saco-de-bondades-para-as-empresas-de-energia-eletrica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.notibras.com\/site\/wp-content\/uploads\/2014\/02\/energia-20111129075906.jpg","articleSection":["Opina a\u00ed"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.notibras.com\/site\/saco-de-bondades-para-as-empresas-de-energia-eletrica\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.notibras.com\/site\/saco-de-bondades-para-as-empresas-de-energia-eletrica\/","url":"https:\/\/www.notibras.com\/site\/saco-de-bondades-para-as-empresas-de-energia-eletrica\/","name":"Pronto. Um saco de bondades para as empresas de energia el\u00e9trica - Notibras","isPartOf":{"@id":"https:\/\/www.notibras.com\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.notibras.com\/site\/saco-de-bondades-para-as-empresas-de-energia-eletrica\/#primaryimage"},"image":{"@id":"https:\/\/www.notibras.com\/site\/saco-de-bondades-para-as-empresas-de-energia-eletrica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.notibras.com\/site\/wp-content\/uploads\/2014\/02\/energia-20111129075906.jpg","datePublished":"2014-02-04T20:36:02+00:00","dateModified":"2014-02-04T20:58:55+00:00","breadcrumb":{"@id":"https:\/\/www.notibras.com\/site\/saco-de-bondades-para-as-empresas-de-energia-eletrica\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.notibras.com\/site\/saco-de-bondades-para-as-empresas-de-energia-eletrica\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.notibras.com\/site\/saco-de-bondades-para-as-empresas-de-energia-eletrica\/#primaryimage","url":"https:\/\/www.notibras.com\/site\/wp-content\/uploads\/2014\/02\/energia-20111129075906.jpg","contentUrl":"https:\/\/www.notibras.com\/site\/wp-content\/uploads\/2014\/02\/energia-20111129075906.jpg","width":680,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/www.notibras.com\/site\/saco-de-bondades-para-as-empresas-de-energia-eletrica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.notibras.com\/site\/"},{"@type":"ListItem","position":2,"name":"Pronto. Um saco de bondades para as empresas de energia el\u00e9trica"}]},{"@type":"WebSite","@id":"https:\/\/www.notibras.com\/site\/#website","url":"https:\/\/www.notibras.com\/site\/","name":"Notibras","description":"Not\u00edcias de Bras\u00edlia, do Brasil e do Mundo","publisher":{"@id":"https:\/\/www.notibras.com\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.notibras.com\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.notibras.com\/site\/#organization","name":"Grupo Notibras de Comunica\u00e7\u00e3o","url":"https:\/\/www.notibras.com\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.notibras.com\/site\/#\/schema\/logo\/image\/","url":"https:\/\/www.notibras.com\/site\/wp-content\/uploads\/2023\/01\/notibras23.png","contentUrl":"https:\/\/www.notibras.com\/site\/wp-content\/uploads\/2023\/01\/notibras23.png","width":350,"height":87,"caption":"Grupo Notibras de Comunica\u00e7\u00e3o"},"image":{"@id":"https:\/\/www.notibras.com\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/notibras\/","https:\/\/x.com\/Notibras","https:\/\/www.instagram.com\/notibras\/"]},{"@type":"Person","@id":"https:\/\/www.notibras.com\/site\/#\/schema\/person\/36ab0979449956132d3e5b517ea76ac8","name":"Reda\u00e7\u00e3o","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/e0a867bdedb85fd243eadf09663511f96fc81e0720a4a42581f334ad4303aa6b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e0a867bdedb85fd243eadf09663511f96fc81e0720a4a42581f334ad4303aa6b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e0a867bdedb85fd243eadf09663511f96fc81e0720a4a42581f334ad4303aa6b?s=96&d=mm&r=g","caption":"Reda\u00e7\u00e3o"}}]}},"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/325","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=325"}],"version-history":[{"count":0,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/325\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/326"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=325"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=325"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=325"},{"taxonomy":"tmauthors","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tmauthors?post=325"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}