{"id":394498,"date":"2026-05-13T02:00:18","date_gmt":"2026-05-13T05:00:18","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=394498"},"modified":"2026-05-12T20:51:24","modified_gmt":"2026-05-12T23:51:24","slug":"renato-freitas-e-o-preco-de-enfrentar-privilegios","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/renato-freitas-e-o-preco-de-enfrentar-privilegios\/","title":{"rendered":"Renato Freitas e o pre\u00e7o de enfrentar privil\u00e9gios"},"content":{"rendered":"<p>O Conselho de \u00c9tica da Assembleia Legislativa do Paran\u00e1 aprovou a cassa\u00e7\u00e3o do deputado Renato Freitas sob a alega\u00e7\u00e3o de quebra de decoro parlamentar. A justificativa formal gira em torno de uma confus\u00e3o ocorrida na rua. Mas ningu\u00e9m minimamente atento ao cen\u00e1rio pol\u00edtico acredita que a quest\u00e3o seja apenas essa. Renato incomoda porque \u00e9 um parlamentar combativo, que enfrenta privil\u00e9gios, denuncia abusos e se recusa a moldar sua atua\u00e7\u00e3o para agradar os grupos tradicionais de poder. Em ambientes pol\u00edticos acostumados \u00e0 complac\u00eancia e aos acordos silenciosos, quem confronta estruturas costuma virar alvo.<\/p>\n<p>\u00c9 imposs\u00edvel ignorar tamb\u00e9m o componente racial e ideol\u00f3gico dessa persegui\u00e7\u00e3o. Renato Freitas \u00e9 um homem negro, de esquerda, oriundo de movimentos sociais e que ocupa espa\u00e7os historicamente reservados a perfis muito diferentes do seu. Sua presen\u00e7a provoca desconforto justamente porque rompe padr\u00f5es. O rigor seletivo aplicado contra ele escancara uma l\u00f3gica cruel: determinados parlamentares podem protagonizar esc\u00e2ndalos, responder a den\u00fancias graves e continuar preservados politicamente, enquanto outros s\u00e3o tratados como amea\u00e7a permanente. Quando a puni\u00e7\u00e3o parece depender mais de quem a pessoa \u00e9 e do que representa politicamente do que dos fatos em si, o debate deixa de ser jur\u00eddico ou \u00e9tico e passa a ser profundamente pol\u00edtico.<\/p>\n<p>Se a cassa\u00e7\u00e3o de Renato Freitas for confirmada, o epis\u00f3dio entrar\u00e1 para a hist\u00f3ria como uma das p\u00e1ginas mais vergonhosas da pol\u00edtica paranaense recente. N\u00e3o porque parlamentares n\u00e3o devam responder por seus atos, mas porque o contraste ser\u00e1 inevit\u00e1vel diante de tantos outros pol\u00edticos comprovadamente envolvidos em corrup\u00e7\u00e3o, desvios e esc\u00e2ndalos muito mais graves que jamais perderam seus mandatos. A mensagem transmitida \u00e0 sociedade ser\u00e1 devastadora: no Brasil, muitas vezes n\u00e3o \u00e9 a gravidade do ato que define a puni\u00e7\u00e3o, mas sim o inc\u00f4modo pol\u00edtico que determinada figura causa ao sistema.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Conselho de \u00c9tica da Assembleia Legislativa do Paran\u00e1 aprovou a cassa\u00e7\u00e3o do deputado Renato Freitas sob a alega\u00e7\u00e3o de quebra de decoro parlamentar. A justificativa formal gira em torno de uma confus\u00e3o ocorrida na rua. Mas ningu\u00e9m minimamente atento ao cen\u00e1rio pol\u00edtico acredita que a quest\u00e3o seja apenas essa. Renato incomoda porque \u00e9 um [&hellip;]<\/p>\n","protected":false},"author":21,"featured_media":394499,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[235],"tags":[],"class_list":["post-394498","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dona-irene"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/394498","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=394498"}],"version-history":[{"count":2,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/394498\/revisions"}],"predecessor-version":[{"id":394501,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/394498\/revisions\/394501"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/394499"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=394498"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=394498"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=394498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}