{"id":394556,"date":"2026-05-13T07:31:09","date_gmt":"2026-05-13T10:31:09","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=394556"},"modified":"2026-05-13T07:33:23","modified_gmt":"2026-05-13T10:33:23","slug":"bolsonarismo-ve-como-tirar-batom-na-cueca-de-ciro-no-caso-master","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/bolsonarismo-ve-como-tirar-batom-na-cueca-de-ciro-no-caso-master\/","title":{"rendered":"Bolsonarismo v\u00ea como tirar batom na cueca de Ciro no caso Master"},"content":{"rendered":"<p>Da mesma forma que alguns inventivos brasileiros precisam ser estudados pela Nasa, boa parte dos chamados bolsonaristas tem de ser avaliado urgentemente por uma federa\u00e7\u00e3o de psiquiatras, psic\u00f3logos e terapeutas. Ingerir detergente apenas para contestar uma afirma\u00e7\u00e3o do governo ao qual fazem oposi\u00e7\u00e3o n\u00e3o \u00e9 coisa de gente s\u00e9ria, normal ou capacidade cognitiva mediana. Bastam dos neur\u00f4nios para que um menino do Maternal II saiba que qualquer tipo de contamina\u00e7\u00e3o \u00e9 um problema sanit\u00e1rio e n\u00e3o ideol\u00f3gico.<\/p>\n<p>Talvez negando as apar\u00eancias e disfar\u00e7ando as evid\u00eancias, os fan\u00e1ticos acabam por se auto contaminarem negativamente e, sem querer querendo, confirmam o que o restante do Brasil j\u00e1 sabia: o bolsonarismo realmente \u00e9 uma doen\u00e7a cr\u00f4nica, contagiosa e maldita. O problema \u00e9 que, conforme o contato, ela n\u00e3o atinge somente pessoas, mas toda a na\u00e7\u00e3o. Por exemplo, \u00e9 p\u00fablico e not\u00f3rio que o senador Ciro Nogueira \u00e9 suspeito de receber mesada de Daniel Vorcaro para beneficiar o Banco Master no Senado.<\/p>\n<p>Apesar de o batom na cueca ser vermelho, pegajoso e vis\u00edvel, o cl\u00e3 Bolsonaro e seus seguidores continuam fingindo que eles n\u00e3o t\u00eam nada a ver com isso. Tanto que mantiveram a alian\u00e7a Uni\u00e3o-PP com Fl\u00e1vio Bolsonaro. Ap\u00f3s uma r\u00e1pida passada d\u2019olhos nos sites especializados, todos os brasileiros se lembrar\u00e3o que, como ministro, Ciro Nogueira foi o bra\u00e7o direito do governo de Jair Bolsonaro e \u201cvice dos sonhos\u201d do candidato Fl\u00e1vio Bolsonaro. O trabalho sujo de Ciro Nogueira para ajudar o Master \u00e9 a prova de que hoje a maioria dos pol\u00edticos se esmera em benef\u00edcio pr\u00f3prio. E da\u00ed se h\u00e1 eleitores que adoram amar corruptos que dizem odiar a corrup\u00e7\u00e3o?<\/p>\n<p>\u00c9 a certeza de que similares do fict\u00edcio deputado Justo Ver\u00edssimo vivem, povoam o imagin\u00e1rio dos que apostam no caos e, com apoio desses, lotam o Congresso. Para as centenas de eleitos e milh\u00f5es de eleitores inclu\u00eddos no cat\u00e1logo de bebedores de detergentes e outros produtos da marca Yp\u00ea, o povo que se exploda. A \u00edndole desses pol\u00edticos e a de quem os elege fica clara quando eles escolhem o que definem como corrup\u00e7\u00e3o e o que dizem ser persegui\u00e7\u00e3o pol\u00edtica. Triste, mas ainda \u00e9 grande a rela\u00e7\u00e3o dos brasileiros que defendem at\u00e9 a morte os falsos perseguidos, entre eles os donos da Yp\u00ea, financiadores da campanha de Bolsonaro em 2022.<\/p>\n<p>Politizar a bact\u00e9ria \u00e9 minimizar a infinidade de micr\u00f3bios que infestam o Congresso Nacional e o amontoado de germes que habitam a mente nociva e decomposta dos que trabalham contra o Brasil. Como \u00e9 dif\u00edcil saber qual microrganismo causa mais doen\u00e7as, fico com a resposta oficial, segundo a qual bact\u00e9rias n\u00e3o s\u00e3o de esquerda ou de direita. Estultices e ignor\u00e2ncia \u00e0 parte, bact\u00e9ria \u00e9 uma quest\u00e3o de sa\u00fade p\u00fablica. Vale registrar que loucos por detergentes s\u00e3o os mesmos que negaram a Covid-19, cujo v\u00edrus matou mais de 700 mil brasileiros, muitos deles bolsonaristas at\u00e9 debaixo dos tapetes.<\/p>\n<p>Como o melhor modo de ignorar um inimigo ou advers\u00e1rio \u00e9 n\u00e3o se assemelhar a ele, \u00e9 o tenho feito. Por exemplo, parei de dar explica\u00e7\u00f5es ou contra minhas hist\u00f3rias a quem s\u00f3 entende o que quer. A pedido m\u00e9dico, estou me poupando para quando a elei\u00e7\u00e3o chegar. Torcendo para que os id\u00f3latras sem nexo tamb\u00e9m procurem bons psiquiatras, at\u00e9 outubro mantenho todas as minhas certezas sobre a pol\u00edtica, os pol\u00edticos, os politiqueiros e o Banco Master. Uma delas \u00e9 a desnecessidade de o senador Ciro Gomes ser pol\u00edtico. Afinal, com vencimentos da ordem de R$ 500 mil mensais para que ocupar o espa\u00e7o de quem realmente quer trabalhar pelo povo?<\/p>\n<p>&#8230;.<\/p>\n<p><strong>Wenceslau Ara\u00fajo \u00e9 Editor-Chefe de Notibras<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Da mesma forma que alguns inventivos brasileiros precisam ser estudados pela Nasa, boa parte dos chamados bolsonaristas tem de ser avaliado urgentemente por uma federa\u00e7\u00e3o de psiquiatras, psic\u00f3logos e terapeutas. Ingerir detergente apenas para contestar uma afirma\u00e7\u00e3o do governo ao qual fazem oposi\u00e7\u00e3o n\u00e3o \u00e9 coisa de gente s\u00e9ria, normal ou capacidade cognitiva mediana. Bastam [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":394557,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[95],"class_list":["post-394556","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil","tag-capa"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/394556","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=394556"}],"version-history":[{"count":3,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/394556\/revisions"}],"predecessor-version":[{"id":394560,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/394556\/revisions\/394560"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/394557"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=394556"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=394556"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=394556"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}