{"id":403410,"date":"2026-07-15T00:15:20","date_gmt":"2026-07-15T03:15:20","guid":{"rendered":"https:\/\/www.notibras.com\/site\/?p=403410"},"modified":"2026-07-14T22:02:39","modified_gmt":"2026-07-15T01:02:39","slug":"mais-de-900-vagas-de-emprego-disponiveis-nesta-quarta-15","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/mais-de-900-vagas-de-emprego-disponiveis-nesta-quarta-15\/","title":{"rendered":"Mais de 900 vagas de emprego dispon\u00edveis nesta quarta (15)"},"content":{"rendered":"<div class=\"topo\">\n<p>As ag\u00eancias do trabalhador do Distrito Federal oferecem, nesta quarta-feira (15), <a href=\"https:\/\/agenciabrasilia.df.gov.br\/documents\/d\/guest\/vagas-abertas-em-14-07-2026-pdf\">910 vagas<\/a>\u00a0para candidatos em busca de uma oportunidade no mercado de trabalho. As chances contemplam profissionais de diferentes n\u00edveis de escolaridade, com ou sem experi\u00eancia, incluindo quem busca o primeiro emprego.<\/p>\n<p>O maior sal\u00e1rio entre as vagas dispon\u00edveis \u00e9 para o cargo de mec\u00e2nico de manuten\u00e7\u00e3o de m\u00e1quina industrial. S\u00e3o cinco oportunidades, com remunera\u00e7\u00e3o de R$ 8 mil, al\u00e9m de benef\u00edcios.<\/p>\n<p>Outro cargo que se destaca pela quantidade de vagas oferecidas \u00e9 o de operador de caixa, com 211 oportunidades dispon\u00edveis. A remunera\u00e7\u00e3o chega a R$ 1,7 mil, al\u00e9m de benef\u00edcios.<\/p>\n<\/div>\n<div class=\"conteudo col-md-10 mx-auto\">\n<div class=\"text-content\">\n<p>Para participar dos processos seletivos, basta cadastrar o curr\u00edculo no aplicativo da Carteira de Trabalho Digital (CTPS) ou ir a uma das\u00a0<a href=\"https:\/\/sedet.df.gov.br\/agencias\">16 ag\u00eancias do trabalhador<\/a>, das 8h \u00e0s 17h, durante a semana. Mesmo que nenhuma das oportunidades do dia seja atraente ao candidato, o cadastro vale para oportunidades futuras, j\u00e1 que o sistema cruza dados dos concorrentes com o perfil que as empresas procuram.<\/p>\n<\/div>\n<div class=\"text-content\">\n<p>Empregadores e empreendedores que desejam ofertar vagas ou utilizar o espa\u00e7o das ag\u00eancias do trabalhador para as entrevistas podem se cadastrar pessoalmente nas unidades ou pelo\u00a0<a href=\"http:\/\/gcv@sedet.df.gov.br\/\">e-mail<\/a>. Pode ser utilizado, ainda, o\u00a0<a href=\"https:\/\/sedet.df.gov.br\/canal-do-empregador\">Canal do Empregador<\/a>.<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>As ag\u00eancias do trabalhador do Distrito Federal oferecem, nesta quarta-feira (15), 910 vagas\u00a0para candidatos em busca de uma oportunidade no mercado de trabalho. As chances contemplam profissionais de diferentes n\u00edveis de escolaridade, com ou sem experi\u00eancia, incluindo quem busca o primeiro emprego. O maior sal\u00e1rio entre as vagas dispon\u00edveis \u00e9 para o cargo de mec\u00e2nico [&hellip;]<\/p>\n","protected":false},"author":21,"featured_media":402374,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[161],"tags":[],"tmauthors":[306],"class_list":["post-403410","post","type-post","status-publish","format-standard","has-post-thumbnail","category-quadradinho-em-foco"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mais de 900 vagas de emprego dispon\u00edveis nesta quarta (15) - Notibras<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.notibras.com\/site\/mais-de-900-vagas-de-emprego-disponiveis-nesta-quarta-15\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mais de 900 vagas de emprego dispon\u00edveis nesta quarta (15) - Notibras\" \/>\n<meta property=\"og:description\" content=\"As ag\u00eancias do trabalhador do Distrito Federal oferecem, nesta quarta-feira (15), 910 vagas\u00a0para candidatos em busca de uma oportunidade no mercado de trabalho. As chances contemplam profissionais de diferentes n\u00edveis de escolaridade, com ou sem experi\u00eancia, incluindo quem busca o primeiro emprego. O maior sal\u00e1rio entre as vagas dispon\u00edveis \u00e9 para o cargo de mec\u00e2nico [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.notibras.com\/site\/mais-de-900-vagas-de-emprego-disponiveis-nesta-quarta-15\/\" \/>\n<meta property=\"og:site_name\" content=\"Notibras\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/notibras\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-15T03:15:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.notibras.com\/site\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-02-03-at-02.40.31-952x600-1-1-1-1-1-1-2-1-1-1-1-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"952\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eduardo Mart\u00ednez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Notibras\" \/>\n<meta name=\"twitter:site\" content=\"@Notibras\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo Mart\u00ednez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/mais-de-900-vagas-de-emprego-disponiveis-nesta-quarta-15\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/mais-de-900-vagas-de-emprego-disponiveis-nesta-quarta-15\\\/\"},\"author\":{\"name\":\"Eduardo Mart\u00ednez\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#\\\/schema\\\/person\\\/5b7fabf2aedc3ada2105f03b22b4d3dd\"},\"headline\":\"Mais de 900 vagas de emprego dispon\u00edveis nesta quarta (15)\",\"datePublished\":\"2026-07-15T03:15:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/mais-de-900-vagas-de-emprego-disponiveis-nesta-quarta-15\\\/\"},\"wordCount\":224,\"publisher\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/mais-de-900-vagas-de-emprego-disponiveis-nesta-quarta-15\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/WhatsApp-Image-2026-02-03-at-02.40.31-952x600-1-1-1-1-1-1-2-1-1-1-1-1.jpeg\",\"articleSection\":[\"Quadradinho em Foco\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/mais-de-900-vagas-de-emprego-disponiveis-nesta-quarta-15\\\/\",\"url\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/mais-de-900-vagas-de-emprego-disponiveis-nesta-quarta-15\\\/\",\"name\":\"Mais de 900 vagas de emprego dispon\u00edveis nesta quarta (15) - Notibras\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/mais-de-900-vagas-de-emprego-disponiveis-nesta-quarta-15\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/mais-de-900-vagas-de-emprego-disponiveis-nesta-quarta-15\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/WhatsApp-Image-2026-02-03-at-02.40.31-952x600-1-1-1-1-1-1-2-1-1-1-1-1.jpeg\",\"datePublished\":\"2026-07-15T03:15:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/mais-de-900-vagas-de-emprego-disponiveis-nesta-quarta-15\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.notibras.com\\\/site\\\/mais-de-900-vagas-de-emprego-disponiveis-nesta-quarta-15\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/mais-de-900-vagas-de-emprego-disponiveis-nesta-quarta-15\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/WhatsApp-Image-2026-02-03-at-02.40.31-952x600-1-1-1-1-1-1-2-1-1-1-1-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/WhatsApp-Image-2026-02-03-at-02.40.31-952x600-1-1-1-1-1-1-2-1-1-1-1-1.jpeg\",\"width\":952,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/mais-de-900-vagas-de-emprego-disponiveis-nesta-quarta-15\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mais de 900 vagas de emprego dispon\u00edveis nesta quarta (15)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/\",\"name\":\"Notibras\",\"description\":\"Not\u00edcias de Bras\u00edlia, do Brasil e do Mundo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#organization\",\"name\":\"Grupo Notibras de Comunica\u00e7\u00e3o\",\"url\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/notibras23.png\",\"contentUrl\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/notibras23.png\",\"width\":350,\"height\":87,\"caption\":\"Grupo Notibras de Comunica\u00e7\u00e3o\"},\"image\":{\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/notibras\\\/\",\"https:\\\/\\\/x.com\\\/Notibras\",\"https:\\\/\\\/www.instagram.com\\\/notibras\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.notibras.com\\\/site\\\/#\\\/schema\\\/person\\\/5b7fabf2aedc3ada2105f03b22b4d3dd\",\"name\":\"Eduardo Mart\u00ednez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7902f906289926289cbcda644b5197c796b893c6ffd7b9a536a42d290f7704a0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7902f906289926289cbcda644b5197c796b893c6ffd7b9a536a42d290f7704a0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7902f906289926289cbcda644b5197c796b893c6ffd7b9a536a42d290f7704a0?s=96&d=mm&r=g\",\"caption\":\"Eduardo Mart\u00ednez\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mais de 900 vagas de emprego dispon\u00edveis nesta quarta (15) - Notibras","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.notibras.com\/site\/mais-de-900-vagas-de-emprego-disponiveis-nesta-quarta-15\/","og_locale":"pt_BR","og_type":"article","og_title":"Mais de 900 vagas de emprego dispon\u00edveis nesta quarta (15) - Notibras","og_description":"As ag\u00eancias do trabalhador do Distrito Federal oferecem, nesta quarta-feira (15), 910 vagas\u00a0para candidatos em busca de uma oportunidade no mercado de trabalho. As chances contemplam profissionais de diferentes n\u00edveis de escolaridade, com ou sem experi\u00eancia, incluindo quem busca o primeiro emprego. O maior sal\u00e1rio entre as vagas dispon\u00edveis \u00e9 para o cargo de mec\u00e2nico [&hellip;]","og_url":"https:\/\/www.notibras.com\/site\/mais-de-900-vagas-de-emprego-disponiveis-nesta-quarta-15\/","og_site_name":"Notibras","article_publisher":"https:\/\/www.facebook.com\/notibras\/","article_published_time":"2026-07-15T03:15:20+00:00","og_image":[{"width":952,"height":600,"url":"https:\/\/www.notibras.com\/site\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-02-03-at-02.40.31-952x600-1-1-1-1-1-1-2-1-1-1-1-1.jpeg","type":"image\/jpeg"}],"author":"Eduardo Mart\u00ednez","twitter_card":"summary_large_image","twitter_creator":"@Notibras","twitter_site":"@Notibras","twitter_misc":{"Escrito por":"Eduardo Mart\u00ednez","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.notibras.com\/site\/mais-de-900-vagas-de-emprego-disponiveis-nesta-quarta-15\/#article","isPartOf":{"@id":"https:\/\/www.notibras.com\/site\/mais-de-900-vagas-de-emprego-disponiveis-nesta-quarta-15\/"},"author":{"name":"Eduardo Mart\u00ednez","@id":"https:\/\/www.notibras.com\/site\/#\/schema\/person\/5b7fabf2aedc3ada2105f03b22b4d3dd"},"headline":"Mais de 900 vagas de emprego dispon\u00edveis nesta quarta (15)","datePublished":"2026-07-15T03:15:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.notibras.com\/site\/mais-de-900-vagas-de-emprego-disponiveis-nesta-quarta-15\/"},"wordCount":224,"publisher":{"@id":"https:\/\/www.notibras.com\/site\/#organization"},"image":{"@id":"https:\/\/www.notibras.com\/site\/mais-de-900-vagas-de-emprego-disponiveis-nesta-quarta-15\/#primaryimage"},"thumbnailUrl":"https:\/\/www.notibras.com\/site\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-02-03-at-02.40.31-952x600-1-1-1-1-1-1-2-1-1-1-1-1.jpeg","articleSection":["Quadradinho em Foco"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.notibras.com\/site\/mais-de-900-vagas-de-emprego-disponiveis-nesta-quarta-15\/","url":"https:\/\/www.notibras.com\/site\/mais-de-900-vagas-de-emprego-disponiveis-nesta-quarta-15\/","name":"Mais de 900 vagas de emprego dispon\u00edveis nesta quarta (15) - Notibras","isPartOf":{"@id":"https:\/\/www.notibras.com\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.notibras.com\/site\/mais-de-900-vagas-de-emprego-disponiveis-nesta-quarta-15\/#primaryimage"},"image":{"@id":"https:\/\/www.notibras.com\/site\/mais-de-900-vagas-de-emprego-disponiveis-nesta-quarta-15\/#primaryimage"},"thumbnailUrl":"https:\/\/www.notibras.com\/site\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-02-03-at-02.40.31-952x600-1-1-1-1-1-1-2-1-1-1-1-1.jpeg","datePublished":"2026-07-15T03:15:20+00:00","breadcrumb":{"@id":"https:\/\/www.notibras.com\/site\/mais-de-900-vagas-de-emprego-disponiveis-nesta-quarta-15\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.notibras.com\/site\/mais-de-900-vagas-de-emprego-disponiveis-nesta-quarta-15\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.notibras.com\/site\/mais-de-900-vagas-de-emprego-disponiveis-nesta-quarta-15\/#primaryimage","url":"https:\/\/www.notibras.com\/site\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-02-03-at-02.40.31-952x600-1-1-1-1-1-1-2-1-1-1-1-1.jpeg","contentUrl":"https:\/\/www.notibras.com\/site\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-02-03-at-02.40.31-952x600-1-1-1-1-1-1-2-1-1-1-1-1.jpeg","width":952,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/www.notibras.com\/site\/mais-de-900-vagas-de-emprego-disponiveis-nesta-quarta-15\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.notibras.com\/site\/"},{"@type":"ListItem","position":2,"name":"Mais de 900 vagas de emprego dispon\u00edveis nesta quarta (15)"}]},{"@type":"WebSite","@id":"https:\/\/www.notibras.com\/site\/#website","url":"https:\/\/www.notibras.com\/site\/","name":"Notibras","description":"Not\u00edcias de Bras\u00edlia, do Brasil e do Mundo","publisher":{"@id":"https:\/\/www.notibras.com\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.notibras.com\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.notibras.com\/site\/#organization","name":"Grupo Notibras de Comunica\u00e7\u00e3o","url":"https:\/\/www.notibras.com\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.notibras.com\/site\/#\/schema\/logo\/image\/","url":"https:\/\/www.notibras.com\/site\/wp-content\/uploads\/2023\/01\/notibras23.png","contentUrl":"https:\/\/www.notibras.com\/site\/wp-content\/uploads\/2023\/01\/notibras23.png","width":350,"height":87,"caption":"Grupo Notibras de Comunica\u00e7\u00e3o"},"image":{"@id":"https:\/\/www.notibras.com\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/notibras\/","https:\/\/x.com\/Notibras","https:\/\/www.instagram.com\/notibras\/"]},{"@type":"Person","@id":"https:\/\/www.notibras.com\/site\/#\/schema\/person\/5b7fabf2aedc3ada2105f03b22b4d3dd","name":"Eduardo Mart\u00ednez","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/7902f906289926289cbcda644b5197c796b893c6ffd7b9a536a42d290f7704a0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7902f906289926289cbcda644b5197c796b893c6ffd7b9a536a42d290f7704a0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7902f906289926289cbcda644b5197c796b893c6ffd7b9a536a42d290f7704a0?s=96&d=mm&r=g","caption":"Eduardo Mart\u00ednez"}}]}},"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/403410","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=403410"}],"version-history":[{"count":4,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/403410\/revisions"}],"predecessor-version":[{"id":403412,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/403410\/revisions\/403412"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/402374"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=403410"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=403410"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=403410"},{"taxonomy":"tmauthors","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tmauthors?post=403410"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}