{"id":84076,"date":"2016-01-11T01:30:47","date_gmt":"2016-01-11T03:30:47","guid":{"rendered":"http:\/\/www.notibras.com\/site\/?p=84076"},"modified":"2016-01-11T01:30:47","modified_gmt":"2016-01-11T03:30:47","slug":"hamm-com-don-draper-vence-pablo-escobar-de-wagner-moura","status":"publish","type":"post","link":"https:\/\/www.notibras.com\/site\/hamm-com-don-draper-vence-pablo-escobar-de-wagner-moura\/","title":{"rendered":"Hamm, com Don Draper, vence Pablo Escobar de Wagner Moura"},"content":{"rendered":"<p>O ator Jon Hamm ganhou o Globo de Ouro de melhor ator de s\u00e9rie dram\u00e1tica neste domingo (10) por sua atua\u00e7\u00e3o como Don Draper na s\u00e9tima e \u00faltima temporada de &#8220;Mad Men&#8221;, que foi encerrada em 2015.<\/p>\n<p>Ele derrotou o brasileiro Wagner Moura, indicado pelo papel de Pablo Escobar na s\u00e9rie &#8220;Narcos&#8221;, do Netflix. Tamb\u00e9m concorriam na categoria os atores Liev Shreiber (&#8220;Ray Donovan&#8221;), Bob Odenkirk (&#8220;Better Call Saul&#8221;) e Rami Malek (&#8220;Mr. Robot). Foi a primeira vez que o Brasil teve um representante na festa da Associa\u00e7\u00e3o dos Correspondentes Estrangeiros de Hollywood desde 1999, quando &#8220;Central do Brasil&#8221; venceu o pr\u00eamio de melhor filme estrangeiro.<\/p>\n<p>Em seu discurso de aceita\u00e7\u00e3o, Hamm agradeceu a <span class=\"st\">Associa\u00e7\u00e3o dos Correspondentes Estrangeiros de Hollywood por &#8220;inclu\u00ed-lo no grupo de atores talentosos indicados&#8221;. O ator ainda disse obrigado ao roteirista Matthew Einer por ter escrito um personagem &#8220;t\u00e3o horroroso&#8221; e t\u00ea-lo escolhido para interpret\u00e1-lo.<\/span><\/p>\n<p><span class=\"st\">&#8220;Tamb\u00e9m gostaria de agradec\u00ea-lo por n\u00e3o acatar minha sugest\u00e3o de tocar Chumbawamba&#8221; no final&#8221;, brincou, fazendo refer\u00eancia \u00e0 cena que encerra a s\u00e9rie, com uma propaganda da Coca Cola com a can\u00e7\u00e3o\u00a0<\/span>&#8220;I&#8217;d Like to Buy the World a Coke&#8221;.<\/p>\n<p><span class=\"st\">Hamm venceu o Globo de Ouro em 2008, ano em que &#8220;Mad Men&#8221; estreou.<\/span><\/p>\n<p><strong>Cinema &#8211;\u00a0<\/strong>Nas categorias de cinema, um dos grandes destaques da noite ficou com Sylvester\u00a0Stallone, que voltou ao Globo de Ouro ap\u00f3s 39 anos pelo mesmo papel a que foi indicado como melhor ator em 1977, com\u00a0&#8220;Rocky: Um Lutador&#8221;. Desta vez, Stallone\u00a0ficou com o pr\u00eamio de melhor ator coadjuvante por &#8220;Creed: Nascido para Lutar&#8221;.<\/p>\n<p>Matt\u00a0Damon\u00a0foi premiado como melhor ator de com\u00e9dia ou musical por &#8220;Perdido em Marte&#8221;, e Kate Winslet foi escolhida melhor atriz coadjuvante por &#8220;Steve Jobs&#8221;.<\/p>\n<p>O veterano Ennio\u00a0Morricone, famoso pelas trilhas sonoras dos faroestes espaguetes de Sergio\u00a0Leone nos anos 1960, pela primeira vez venceu um pr\u00eamio hollywoodiano pela trilha sonora de &#8220;Os Oito Odiados&#8221;, de Quentin Tarantino, que recebeu o pr\u00eamio por ele. O novo filme de Tarantino foi o primeiro trabalho de Morricone em 40 anos. Anteriormente, o compositor apenas havia recebido um Oscar honor\u00e1rio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O ator Jon Hamm ganhou o Globo de Ouro de melhor ator de s\u00e9rie dram\u00e1tica neste domingo (10) por sua atua\u00e7\u00e3o como Don Draper na s\u00e9tima e \u00faltima temporada de &#8220;Mad Men&#8221;, que foi encerrada em 2015. Ele derrotou o brasileiro Wagner Moura, indicado pelo papel de Pablo Escobar na s\u00e9rie &#8220;Narcos&#8221;, do Netflix. Tamb\u00e9m [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":84077,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[20],"tags":[],"class_list":["post-84076","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mulher-turismo-e-lazer"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/84076","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/comments?post=84076"}],"version-history":[{"count":1,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/84076\/revisions"}],"predecessor-version":[{"id":84078,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/posts\/84076\/revisions\/84078"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media\/84077"}],"wp:attachment":[{"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/media?parent=84076"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/categories?post=84076"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notibras.com\/site\/wp-json\/wp\/v2\/tags?post=84076"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}